{"id":1339,"date":"2018-07-17T17:13:42","date_gmt":"2018-07-17T15:13:42","guid":{"rendered":"https:\/\/2018.verona.wordcamp.org\/?post_type=wcb_session&#038;p=1339"},"modified":"2018-10-08T20:47:00","modified_gmt":"2018-10-08T18:47:00","slug":"great-experience-la-strategia-tra-ux-e-seo","status":"publish","type":"wcb_session","link":"https:\/\/verona.wordcamp.org\/2018\/session\/great-experience-la-strategia-tra-ux-e-seo\/","title":{"rendered":"GREAT EXPERIENCE: la strategia tra UX e SEO [45&#8242;]"},"content":{"rendered":"<p>Quando si parla di esperienza delle persone il processo da considerare \u00e8 ampio e lungo; sicuramente non solo orientato al web.<br \/>\nCapire quando inizia e quando finisce l\u2019esperienza \u00e8 una grande sfida per chi lavora nel mondo digitale e ci sono processi, metodi e strumenti che ci possono aiutare in questo.<br \/>\nMa dove sta il confine tra l\u2019esperienze della persone e l\u2019ottimizzazione del sito web nel motore di ricerca?<br \/>\nAvere degli obiettivi e una strategia aiutano a migliorare l\u2019esperienza delle persone, a migliorare la SEO e ad aumentare le conversioni?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quando si parla di esperienza delle persone il processo da considerare \u00e8 ampio e lungo; sicuramente non solo orientato al web. Capire quando inizia e quando finisce l\u2019esperienza \u00e8 una grande sfida per chi lavora nel mondo digitale e ci &hellip; <a href=\"https:\/\/verona.wordcamp.org\/2018\/session\/great-experience-la-strategia-tra-ux-e-seo\/\">Continue reading <span class=\"assistive-text\">GREAT EXPERIENCE: la strategia tra UX e SEO [45&#8242;]<\/span>  <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":16203028,"featured_media":0,"template":"","meta":{"_crdt_document":"","_wcpt_session_time":1539433800,"_wcpt_session_duration":3000,"_wcpt_session_type":"session","_wcpt_session_slides":"","_wcpt_session_video":"","_wcpt_speaker_id":[1338],"footnotes":""},"session_track":[13412],"session_category":[],"class_list":["post-1339","wcb_session","type-wcb_session","status-publish","hentry","wcb_track-track-2"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheLnV-lB","session_date_time":{"date":"13\/10\/2018","time":"14:30"},"session_speakers":[{"id":"1338","slug":"chiaradanese","name":"Chiara Danese","link":"https:\/\/verona.wordcamp.org\/2018\/speaker\/chiaradanese\/"}],"session_cats_rendered":null,"_links":{"self":[{"href":"https:\/\/verona.wordcamp.org\/2018\/wp-json\/wp\/v2\/sessions\/1339","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/verona.wordcamp.org\/2018\/wp-json\/wp\/v2\/sessions"}],"about":[{"href":"https:\/\/verona.wordcamp.org\/2018\/wp-json\/wp\/v2\/types\/wcb_session"}],"version-history":[{"count":8,"href":"https:\/\/verona.wordcamp.org\/2018\/wp-json\/wp\/v2\/sessions\/1339\/revisions"}],"predecessor-version":[{"id":2021,"href":"https:\/\/verona.wordcamp.org\/2018\/wp-json\/wp\/v2\/sessions\/1339\/revisions\/2021"}],"speakers":[{"embeddable":true,"href":"https:\/\/verona.wordcamp.org\/2018\/wp-json\/wp\/v2\/speakers\/1338"}],"author":[{"embeddable":true,"href":"https:\/\/verona.wordcamp.org\/2018\/wp-json\/wporg\/v1\/users\/chiaradanese"}],"wp:attachment":[{"href":"https:\/\/verona.wordcamp.org\/2018\/wp-json\/wp\/v2\/media?parent=1339"}],"wp:term":[{"taxonomy":"wcb_track","embeddable":true,"href":"https:\/\/verona.wordcamp.org\/2018\/wp-json\/wp\/v2\/session_track?post=1339"},{"taxonomy":"wcb_session_category","embeddable":true,"href":"https:\/\/verona.wordcamp.org\/2018\/wp-json\/wp\/v2\/session_category?post=1339"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}