{"id":177,"date":"2018-03-22T07:13:24","date_gmt":"2018-03-22T07:13:24","guid":{"rendered":"https:\/\/2018.verona.wordcamp.org\/?page_id=177"},"modified":"2018-04-24T13:08:27","modified_gmt":"2018-04-24T11:08:27","slug":"codice-di-condotta","status":"publish","type":"page","link":"https:\/\/verona.wordcamp.org\/2018\/codice-di-condotta\/","title":{"rendered":"Codice di condotta"},"content":{"rendered":"<div class=\"articolo\">\r\n<h2 class=\"wp-block-heading\">1. Scopo<\/h2>\r\n\r\n<p>&nbsp;<\/p>\r\n\r\n<p class=\"wp-block-paragraph\">WordCamp Verona ritiene che la<strong>\u00a0community debba essere aperta a tutti<\/strong>. Per questo ci siamo impegnati a fornire un ambiente amichevole, sicuro ed accogliente, indipendentemente da sesso, orientamento sessuale, disabilit\u00e0, etnia, religione, sistema operativo preferito, linguaggio di programmazione o editor di testo.<\/p>\r\n\r\n<p class=\"wp-block-paragraph\">Questo codice di condotta delinea il comportamento che ci aspettiamo dai partecipanti, nonch\u00e9 le conseguenze in caso di comportamento inaccettabile.<\/p>\r\n\r\n<p class=\"wp-block-paragraph\">Invitiamo tutti gli sponsor, i volontari, gli speakers e i partecipanti ad aiutarci a realizzare un evento sicuro e positivo per tutti.<\/p>\r\n\r\n<p>&nbsp;<\/p>\r\n\r\n<h2 class=\"wp-block-heading\">2. Cittadinanza open source<\/h2>\r\n\r\n<p>&nbsp;<\/p>\r\n\r\n<p class=\"wp-block-paragraph\">Ulteriore obiettivo di questo codice di condotta \u00e8 di aumentare la partecipazione all\u2019Open Source, incoraggiando i partecipanti a dare riconoscimento e rafforzare la relazione tra ci\u00f2 che viene fatto e la Community in generale.<\/p>\r\n\r\n<p class=\"wp-block-paragraph\">Per raggiungere questo obiettivo, gli organizzatori di WordCamp Verona raccoglieranno i nomi di partecipanti che si sono distinti e\u00a0li ringrazieranno su questo sito a fine evento.<\/p>\r\n\r\n<p class=\"wp-block-paragraph\">Se notate qualcuno che sta facendo uno sforzo in pi\u00f9 per garantire che la nostra Community sia accogliente, cordiale e incoraggi tutti i partecipanti a contribuire nella misura pi\u00f9 ampia, vogliamo conoscerlo!\u00a0\u00c8 possibile candidare qualcuno al desk di registrazione\u00a0o\u00a0<a href=\"mailto:verona@wordcamp.org\">contattandoci via email<\/a>.<\/p>\r\n\r\n<p>&nbsp;<\/p>\r\n\r\n<h2 class=\"wp-block-heading\">3. Comportamenti attesi<\/h2>\r\n\r\n<p>&nbsp;<\/p>\r\n\r\n<ul class=\"wp-block-list\">\r\n<li>Sii premuroso, rispettoso e collaborativo.<\/li>\r\n<li>Evita comportamenti e linguaggio umilianti, discriminatori o molesti.<\/li>\r\n<li>Sii consapevole dell\u2019ambiente circostante e degli altri partecipanti. Qualora notassi una situazione pericolosa o qualcuno in difficolt\u00e0, avvisa subito gli organizzatori.<\/li>\r\n<li>Partecipa in modo autentico ed attivo. Cos\u00ec facendo contribuirai a creare WordCamp Verona e renderlo tuo.<\/li>\r\n<\/ul>\r\n\r\n<p>&nbsp;<\/p>\r\n\r\n<h2 class=\"wp-block-heading\">4. Comportamenti non accettabili<\/h2>\r\n\r\n<p>&nbsp;<\/p>\r\n\r\n<p class=\"wp-block-paragraph\">I comportamenti non accettabili includono: intimidazioni, offese, violenze, discriminazioni, comportamenti offensivi o umilianti nei confronti dei partecipanti al WordCamp Verona e agli eventi correlati. Tutte le aree adibite a WordCamp Verona possono essere condivise con altre persone; ci aspettiamo tu sia rispettoso verso tutti i frequentatori di questi luoghi.<\/p>\r\n\r\n<p class=\"wp-block-paragraph\">Le molestie possono includere: commenti verbali offensivi legati a genere, orientamento sessuale, razza, religione e disabilit\u00e0; uso inadeguato di nudo e\/o di immagini sessuali negli spazi pubblici (comprese le slide di presentazione); intimidazione intenzionale, stalking; fotografie o video inadeguati; interruzione prolungata di talk o altri eventi; contatto fisico inadeguato e attenzioni sessuali non gradite.<\/p>\r\n\r\n<p>&nbsp;<\/p>\r\n\r\n<h2 class=\"wp-block-heading\">5. Conseguenze per i comportamenti non accettabili<\/h2>\r\n\r\n<p>&nbsp;<\/p>\r\n\r\n<p class=\"wp-block-paragraph\">Non\u00a0saranno tollerati comportamenti non accettabili n\u00e9 da parte di partecipanti, organizzatori, personale della sede o sponsor, n\u00e9 da altri avventori nelle aree di WordCamp Verona.<\/p>\r\n\r\n<p class=\"wp-block-paragraph\">Chiunque venga invitato a cessare un comportamento non accettabile deve eseguire immediatamente.<\/p>\r\n\r\n<p class=\"wp-block-paragraph\">Se un partecipante tiene un comportamento non accettabile, gli organizzatori della conferenza possono prendere qualsiasi misura ritengano opportuna, fino all\u2019espulsione dall\u2019evento senza preavviso o rimborso.<\/p>\r\n\r\n<p>&nbsp;<\/p>\r\n\r\n<h2 class=\"wp-block-heading\">6. Cosa fare se sei testimone o oggetto di un comportamento non accettabile<\/h2>\r\n\r\n<p>&nbsp;<\/p>\r\n\r\n<p class=\"wp-block-paragraph\">Se sei vittima o se noti qualcuno che tiene un comportamento non accettabile, avvisa subito l\u2019Organizzazione. Allo stesso modo se hai qualsiasi altro problema.<\/p>\r\n\r\n<p class=\"wp-block-paragraph\">Il team di WordCamp Verona sar\u00e0 a disposizione per aiutare i partecipanti a contattare le forze dell\u2019ordine locali, per dare passaggi o per aiutare in altro modo coloro che subiscono un comportamento inaccettabile, perch\u00e9 si sentano al sicuro per tutta la durata dell\u2019evento.<\/p>\r\n\r\n<p class=\"wp-block-paragraph\">Ogni volontario pu\u00f2 metterti in contatto con un membro dell\u2019Organizzazione. Puoi anche recarti al Registration Desk e chiedere degli organizzatori.<\/p>\r\n\r\n<p>&nbsp;<\/p>\r\n\r\n<h2 class=\"wp-block-heading\">7. Ambito di applicazione<\/h2>\r\n\r\n<p class=\"wp-block-paragraph\">Ci aspettiamo che tutti i partecipanti all\u2019evento (sponsor, volontari, speakers, partecipanti ed altri ospiti) rispettino questo codice di condotta.<\/p>\r\n\r\n<p>&nbsp;<\/p>\r\n\r\n<h2 class=\"wp-block-heading\">8. Contatti<\/h2>\r\n\r\n<p>Per informazioni sul codice di condotta o per riportare un incidente ti pregiamo di mandarci una\u00a0<a href=\"mailto:verona@wordcamp.org\">mail<\/a>.<\/p>\r\n<p>&nbsp;<\/p>\r\n\r\n<h2 class=\"wp-block-heading\">9. Licenza e attribuzione<\/h2>\r\n\r\n<p class=\"wp-block-paragraph\">Il presente Codice di condotta \u00e8 ispirato dall\u2019importante lavoro di Open Source Bridge. L\u2019originale \u00e8 disponibile all\u2019indirizzo\u00a0<a href=\"http:\/\/opensourcebridge.org\/about\/code-of-conduct\/\">http:\/\/opensourcebridge.org\/about\/code-of-conduct\/<\/a>\u00a0ed \u00e8 rilasciato sotto\u00a0<a href=\"http:\/\/creativecommons.org\/licenses\/by-sa\/3.0\/\">Creative Commons Attribution-ShareAlike<\/a>.<\/p><\/div>","protected":false},"excerpt":{"rendered":"<p>1. Scopo &nbsp; WordCamp Verona ritiene che la\u00a0community debba essere aperta a tutti. Per questo ci siamo impegnati a fornire un ambiente amichevole, sicuro ed accogliente, indipendentemente da sesso, orientamento sessuale, disabilit\u00e0, etnia, religione, sistema operativo preferito, linguaggio di programmazione &hellip; <a href=\"https:\/\/verona.wordcamp.org\/2018\/codice-di-condotta\/\">Continue reading <span class=\"assistive-text\">Codice di condotta<\/span>  <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":14993411,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_crdt_document":"","footnotes":""},"class_list":["post-177","page","type-page","status-publish","hentry"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/PheLnV-2R","_links":{"self":[{"href":"https:\/\/verona.wordcamp.org\/2018\/wp-json\/wp\/v2\/pages\/177","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/verona.wordcamp.org\/2018\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/verona.wordcamp.org\/2018\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/verona.wordcamp.org\/2018\/wp-json\/wp\/v2\/users\/14993411"}],"replies":[{"embeddable":true,"href":"https:\/\/verona.wordcamp.org\/2018\/wp-json\/wp\/v2\/comments?post=177"}],"version-history":[{"count":8,"href":"https:\/\/verona.wordcamp.org\/2018\/wp-json\/wp\/v2\/pages\/177\/revisions"}],"predecessor-version":[{"id":772,"href":"https:\/\/verona.wordcamp.org\/2018\/wp-json\/wp\/v2\/pages\/177\/revisions\/772"}],"wp:attachment":[{"href":"https:\/\/verona.wordcamp.org\/2018\/wp-json\/wp\/v2\/media?parent=177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}